{"id":25592,"date":"2025-04-18T12:57:55","date_gmt":"2025-04-18T12:57:55","guid":{"rendered":"https:\/\/mimarmodels.sa\/?page_id=25592"},"modified":"2025-04-23T12:35:25","modified_gmt":"2025-04-23T12:35:25","slug":"ezdipark","status":"publish","type":"page","link":"https:\/\/mimarmodels.sa\/en\/ezdipark\/","title":{"rendered":"Ezdipark"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25592\" class=\"elementor elementor-25592\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e28ce0 project-temp-item e-flex e-con-boxed e-con e-parent\" data-id=\"8e28ce0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dab5fff e-con-full e-flex e-con e-child\" data-id=\"dab5fff\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6da9c32 cross-icon-stt elementor-widget elementor-widget-button\" data-id=\"6da9c32\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mimarmodels.sa\/entertainment\/#projects\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"124px\" height=\"124px\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"SVGRepo_bgCarrier\" stroke-width=\"0\"><\/g><g id=\"SVGRepo_tracerCarrier\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/g><g id=\"SVGRepo_iconCarrier\"><path d=\"M16 8L8 16M8.00001 8L16 16\" stroke=\"#8F8F8E\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-074a1d0 e-flex e-con-boxed e-con e-child\" data-id=\"074a1d0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68cd28b elementor-widget elementor-widget-htmega-thumbgallery-addons\" data-id=\"68cd28b\" data-element_type=\"widget\" data-widget_type=\"htmega-thumbgallery-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"htmega-sliderarea htmega-thumbnails-style-1 sid68cd28b\" >\n                <div class=\"htb-row row--5 htb-align-items-center mt--40\">\n\n                                            <div class=\"htb-col-lg-10 htb-col-md-10 htb-col-sm-10\">\n                            <div class=\"ht-thumb-gallery\">\n                                <ul dir=\"ltr\" class=\"htmega-thumbgallery-for htmega-arrow-1\" data-settings=\"{&quot;arrows&quot;:true,&quot;arrow_prev_txt&quot;:&quot;&lt;svg class=\\&quot;e-font-icon-svg e-fas-arrow-left\\&quot; viewBox=\\&quot;0 0 448 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M257.5 445.1l-22.2 22.2c-9.4 9.4-24.6 9.4-33.9 0L7 273c-9.4-9.4-9.4-24.6 0-33.9L201.4 44.7c9.4-9.4 24.6-9.4 33.9 0l22.2 22.2c9.5 9.5 9.3 25-.4 34.3L136.6 216H424c13.3 0 24 10.7 24 24v32c0 13.3-10.7 24-24 24H136.6l120.5 114.8c9.8 9.3 10 24.8.4 34.3z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;arrow_next_txt&quot;:&quot;&lt;svg class=\\&quot;e-font-icon-svg e-fas-arrow-right\\&quot; viewBox=\\&quot;0 0 448 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;dots&quot;:false,&quot;autoplay&quot;:false,&quot;autoplay_speed&quot;:3000,&quot;animation_speed&quot;:300,&quot;pause_on_hover&quot;:false,&quot;center_mode&quot;:false,&quot;center_padding&quot;:0,&quot;display_columns&quot;:1,&quot;scroll_columns&quot;:1,&quot;tablet_width&quot;:750,&quot;tablet_display_columns&quot;:1,&quot;tablet_scroll_columns&quot;:1,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1}\" style=\"display:none;\" >\n                                                                            <li>\n                                            <img fetchpriority=\"high\" decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg\" class=\"attachment-full size-full wp-image-25562\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                        <\/li>\n                                                                            <li>\n                                            <img decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4.jpg\" class=\"attachment-full size-full wp-image-25567\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                        <\/li>\n                                                                            <li>\n                                            <img decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4.jpg\" class=\"attachment-full size-full wp-image-25572\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                        <\/li>\n                                                                            <li>\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1.jpg\" class=\"attachment-full size-full wp-image-25577\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                        <\/li>\n                                                                            <li>\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1.jpg\" class=\"attachment-full size-full wp-image-25582\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                        <\/li>\n                                                                    <\/ul>\n\n                            <\/div>\n                        <\/div>\n\n                        <div class=\"htb-col-lg-2 htb-col-md-2 htb-col-sm-2 htmega-nav-col\">\n                            <div class=\"htmega-thumbgallery-nav \" data-navsettings=\"{&quot;navarrows&quot;:false,&quot;navarrow_prev_txt&quot;:&quot;&quot;,&quot;navarrow_next_txt&quot;:&quot;&quot;,&quot;navdots&quot;:false,&quot;navvertical&quot;:true,&quot;navautoplay&quot;:false,&quot;navautoplay_speed&quot;:3000,&quot;navanimation_speed&quot;:300,&quot;navpause_on_hover&quot;:true,&quot;navcenter_mode&quot;:false,&quot;navcenter_padding&quot;:0,&quot;navdisplay_columns&quot;:5,&quot;navscroll_columns&quot;:1,&quot;navtablet_width&quot;:750,&quot;navtablet_display_columns&quot;:5,&quot;navtablet_scroll_columns&quot;:1,&quot;navmobile_width&quot;:767,&quot;navmobile_display_columns&quot;:4,&quot;navmobile_scroll_columns&quot;:2}\" style=\"display:none;\">\n                                                                    <div class=\"small-thumb\">\n                                        <img fetchpriority=\"high\" decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg\" class=\"attachment-full size-full wp-image-25562\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                    <\/div>\n                                                                    <div class=\"small-thumb\">\n                                        <img decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4.jpg\" class=\"attachment-full size-full wp-image-25567\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/02-4-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                    <\/div>\n                                                                    <div class=\"small-thumb\">\n                                        <img decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4.jpg\" class=\"attachment-full size-full wp-image-25572\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/03-4-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                    <\/div>\n                                                                    <div class=\"small-thumb\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1.jpg\" class=\"attachment-full size-full wp-image-25577\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/04-1-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                    <\/div>\n                                                                    <div class=\"small-thumb\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"1111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1.jpg\" class=\"attachment-full size-full wp-image-25582\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1.jpg 1980w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1-768x431.jpg 768w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/05-1-1536x862.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\" \/>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                    \n                    <!-- End Thumb Gallery -->\n                <\/div>\n            <\/div>\n            \n                    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f50c2d e-con-full project-inner-cont e-flex e-con e-child\" data-id=\"3f50c2d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be65928 elementor-widget__width-auto elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"be65928\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EZDIHAR PARK<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1b5cf2 e-con-full e-flex e-con e-child\" data-id=\"e1b5cf2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e741ec7 elementor-widget elementor-widget-heading\" data-id=\"e741ec7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Model Scale: 1:220<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03ea6b4 elementor-widget elementor-widget-heading\" data-id=\"03ea6b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Model Size: 350 X 200 X 13<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddeb293 elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"ddeb293\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">(L X W) CM<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>EZDIHAR PARK Model Scale: 1:220 Model Size: 350 X 200 X 13 (L X W) CM<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-25592","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ezdipark - Mimar Models<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimarmodels.sa\/en\/ezdipark\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ezdipark - Mimar Models\" \/>\n<meta property=\"og:description\" content=\"EZDIHAR PARK Model Scale: 1:220 Model Size: 350 X 200 X 13 (L X W) CM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimarmodels.sa\/en\/ezdipark\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimar Models\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T12:35:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1111\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimarmodels.sa\/en\/ezdipark\/\",\"url\":\"https:\/\/mimarmodels.sa\/en\/ezdipark\/\",\"name\":\"Ezdipark - Mimar Models\",\"isPartOf\":{\"@id\":\"https:\/\/mimarmodels.sa\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimarmodels.sa\/en\/ezdipark\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimarmodels.sa\/en\/ezdipark\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg\",\"datePublished\":\"2025-04-18T12:57:55+00:00\",\"dateModified\":\"2025-04-23T12:35:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mimarmodels.sa\/en\/ezdipark\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimarmodels.sa\/en\/ezdipark\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimarmodels.sa\/en\/ezdipark\/#primaryimage\",\"url\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg\",\"contentUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimarmodels.sa\/en\/ezdipark\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimarmodels.sa\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ezdipark\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimarmodels.sa\/en\/#website\",\"url\":\"https:\/\/mimarmodels.sa\/en\/\",\"name\":\"Mimar Models\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mimarmodels.sa\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimarmodels.sa\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimarmodels.sa\/en\/#organization\",\"name\":\"Mimar Models\",\"url\":\"https:\/\/mimarmodels.sa\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mimarmodels.sa\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg\",\"contentUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg\",\"width\":250,\"height\":76,\"caption\":\"Mimar Models\"},\"image\":{\"@id\":\"https:\/\/mimarmodels.sa\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ezdipark - Mimar Models","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimarmodels.sa\/en\/ezdipark\/","og_locale":"en_US","og_type":"article","og_title":"Ezdipark - Mimar Models","og_description":"EZDIHAR PARK Model Scale: 1:220 Model Size: 350 X 200 X 13 (L X W) CM","og_url":"https:\/\/mimarmodels.sa\/en\/ezdipark\/","og_site_name":"Mimar Models","article_modified_time":"2025-04-23T12:35:25+00:00","og_image":[{"width":1980,"height":1111,"url":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimarmodels.sa\/en\/ezdipark\/","url":"https:\/\/mimarmodels.sa\/en\/ezdipark\/","name":"Ezdipark - Mimar Models","isPartOf":{"@id":"https:\/\/mimarmodels.sa\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimarmodels.sa\/en\/ezdipark\/#primaryimage"},"image":{"@id":"https:\/\/mimarmodels.sa\/en\/ezdipark\/#primaryimage"},"thumbnailUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg","datePublished":"2025-04-18T12:57:55+00:00","dateModified":"2025-04-23T12:35:25+00:00","breadcrumb":{"@id":"https:\/\/mimarmodels.sa\/en\/ezdipark\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimarmodels.sa\/en\/ezdipark\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimarmodels.sa\/en\/ezdipark\/#primaryimage","url":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg","contentUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2025\/04\/01-4.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/mimarmodels.sa\/en\/ezdipark\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimarmodels.sa\/en\/"},{"@type":"ListItem","position":2,"name":"Ezdipark"}]},{"@type":"WebSite","@id":"https:\/\/mimarmodels.sa\/en\/#website","url":"https:\/\/mimarmodels.sa\/en\/","name":"Mimar Models","description":"","publisher":{"@id":"https:\/\/mimarmodels.sa\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimarmodels.sa\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mimarmodels.sa\/en\/#organization","name":"Mimar Models","url":"https:\/\/mimarmodels.sa\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mimarmodels.sa\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg","contentUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg","width":250,"height":76,"caption":"Mimar Models"},"image":{"@id":"https:\/\/mimarmodels.sa\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mimarmodels.sa\/en\/wp-json\/wp\/v2\/pages\/25592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mimarmodels.sa\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mimarmodels.sa\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mimarmodels.sa\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mimarmodels.sa\/en\/wp-json\/wp\/v2\/comments?post=25592"}],"version-history":[{"count":16,"href":"https:\/\/mimarmodels.sa\/en\/wp-json\/wp\/v2\/pages\/25592\/revisions"}],"predecessor-version":[{"id":27615,"href":"https:\/\/mimarmodels.sa\/en\/wp-json\/wp\/v2\/pages\/25592\/revisions\/27615"}],"wp:attachment":[{"href":"https:\/\/mimarmodels.sa\/en\/wp-json\/wp\/v2\/media?parent=25592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}