{"id":26223,"date":"2024-12-10T10:35:25","date_gmt":"2024-12-10T10:35:25","guid":{"rendered":"https:\/\/mimarmodels.sa\/villa-nuun\/"},"modified":"2025-05-05T13:24:43","modified_gmt":"2025-05-05T13:24:43","slug":"villa-nuun","status":"publish","type":"page","link":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/","title":{"rendered":"Villa Nuun"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26223\" class=\"elementor elementor-26223 elementor-10016\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e28ce0 project-temp-item e-flex e-con-boxed e-con e-parent\" data-id=\"8e28ce0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dab5fff e-con-full e-flex e-con e-child\" data-id=\"dab5fff\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ca48f6 cross-icon-stt elementor-widget elementor-widget-button\" data-id=\"0ca48f6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mimarmodels.sa\/es\/villas-y-residencias\/#proyectos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"124px\" height=\"124px\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"SVGRepo_bgCarrier\" stroke-width=\"0\"><\/g><g id=\"SVGRepo_tracerCarrier\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/g><g id=\"SVGRepo_iconCarrier\"><path d=\"M16 8L8 16M8.00001 8L16 16\" stroke=\"#8F8F8E\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-074a1d0 e-flex e-con-boxed e-con e-child\" data-id=\"074a1d0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68cd28b elementor-widget elementor-widget-htmega-thumbgallery-addons\" data-id=\"68cd28b\" data-element_type=\"widget\" data-widget_type=\"htmega-thumbgallery-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"htmega-sliderarea htmega-thumbnails-style-1 sid68cd28b\" >\n                <div class=\"htb-row row--5 htb-align-items-center mt--40\">\n\n                                            <div class=\"htb-col-lg-10 htb-col-md-10 htb-col-sm-10\">\n                            <div class=\"ht-thumb-gallery\">\n                                <ul dir=\"ltr\" class=\"htmega-thumbgallery-for htmega-arrow-1\" data-settings=\"{&quot;arrows&quot;:true,&quot;arrow_prev_txt&quot;:&quot;&lt;svg class=\\&quot;e-font-icon-svg e-fas-arrow-left\\&quot; viewBox=\\&quot;0 0 448 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M257.5 445.1l-22.2 22.2c-9.4 9.4-24.6 9.4-33.9 0L7 273c-9.4-9.4-9.4-24.6 0-33.9L201.4 44.7c9.4-9.4 24.6-9.4 33.9 0l22.2 22.2c9.5 9.5 9.3 25-.4 34.3L136.6 216H424c13.3 0 24 10.7 24 24v32c0 13.3-10.7 24-24 24H136.6l120.5 114.8c9.8 9.3 10 24.8.4 34.3z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;arrow_next_txt&quot;:&quot;&lt;svg class=\\&quot;e-font-icon-svg e-fas-arrow-right\\&quot; viewBox=\\&quot;0 0 448 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;dots&quot;:false,&quot;autoplay&quot;:false,&quot;autoplay_speed&quot;:3000,&quot;animation_speed&quot;:300,&quot;pause_on_hover&quot;:false,&quot;center_mode&quot;:false,&quot;center_padding&quot;:0,&quot;display_columns&quot;:1,&quot;scroll_columns&quot;:1,&quot;tablet_width&quot;:750,&quot;tablet_display_columns&quot;:1,&quot;tablet_scroll_columns&quot;:1,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1}\" style=\"display:none;\" >\n                                                                            <li>\n                                            <img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"606\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg\" class=\"attachment-full size-full wp-image-13561\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg 1080w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01-768x431.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>                                        <\/li>\n                                                                            <li>\n                                            <img decoding=\"async\" width=\"1080\" height=\"606\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02.jpg\" class=\"attachment-full size-full wp-image-13558\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02.jpg 1080w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02-768x431.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>                                        <\/li>\n                                                                            <li>\n                                            <img decoding=\"async\" width=\"1080\" height=\"606\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03.jpg\" class=\"attachment-full size-full wp-image-13559\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03.jpg 1080w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03-768x431.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>                                        <\/li>\n                                                                            <li>\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"606\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04.jpg\" class=\"attachment-full size-full wp-image-13560\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04.jpg 1080w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04-768x431.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>                                        <\/li>\n                                                                    <\/ul>\n\n                            <\/div>\n                        <\/div>\n\n                        <div class=\"htb-col-lg-2 htb-col-md-2 htb-col-sm-2 htmega-nav-col\">\n                            <div class=\"htmega-thumbgallery-nav \" data-navsettings=\"{&quot;navarrows&quot;:false,&quot;navarrow_prev_txt&quot;:&quot;&quot;,&quot;navarrow_next_txt&quot;:&quot;&quot;,&quot;navdots&quot;:false,&quot;navvertical&quot;:true,&quot;navautoplay&quot;:false,&quot;navautoplay_speed&quot;:3000,&quot;navanimation_speed&quot;:300,&quot;navpause_on_hover&quot;:true,&quot;navcenter_mode&quot;:false,&quot;navcenter_padding&quot;:0,&quot;navdisplay_columns&quot;:5,&quot;navscroll_columns&quot;:1,&quot;navtablet_width&quot;:750,&quot;navtablet_display_columns&quot;:5,&quot;navtablet_scroll_columns&quot;:1,&quot;navmobile_width&quot;:767,&quot;navmobile_display_columns&quot;:4,&quot;navmobile_scroll_columns&quot;:2}\" style=\"display:none;\">\n                                                                    <div class=\"small-thumb\">\n                                        <img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"606\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg\" class=\"attachment-full size-full wp-image-13561\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg 1080w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01-768x431.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>                                    <\/div>\n                                                                    <div class=\"small-thumb\">\n                                        <img decoding=\"async\" width=\"1080\" height=\"606\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02.jpg\" class=\"attachment-full size-full wp-image-13558\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02.jpg 1080w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-02-768x431.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>                                    <\/div>\n                                                                    <div class=\"small-thumb\">\n                                        <img decoding=\"async\" width=\"1080\" height=\"606\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03.jpg\" class=\"attachment-full size-full wp-image-13559\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03.jpg 1080w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-03-768x431.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>                                    <\/div>\n                                                                    <div class=\"small-thumb\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"606\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04.jpg\" class=\"attachment-full size-full wp-image-13560\" alt=\"\" srcset=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04.jpg 1080w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04-300x168.jpg 300w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04-1024x575.jpg 1024w, https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-04-768x431.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>                                    <\/div>\n                                                            <\/div>\n                        <\/div>\n                    \n                    <!-- End Thumb Gallery -->\n                <\/div>\n            <\/div>\n            \n                    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f50c2d e-con-full project-inner-cont e-flex e-con e-child\" data-id=\"3f50c2d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be65928 elementor-widget__width-auto elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"be65928\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NUUN VILLA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1b5cf2 e-con-full e-flex e-con e-child\" data-id=\"e1b5cf2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e741ec7 elementor-widget elementor-widget-heading\" data-id=\"e741ec7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Escala del modelo: 1:50<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03ea6b4 elementor-widget elementor-widget-heading\" data-id=\"03ea6b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tama\u00f1o del modelo: 200 X 160 X 21,5<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-578efd8 elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"578efd8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">(L X A) CM<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>NUUN VILLA Escala del modelo: 1:50 Tama\u00f1o del modelo: 200 X 160 X 21,5 (L X A) CM<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-26223","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Villa Nuun - Mimar Models<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Nuun - Mimar Models\" \/>\n<meta property=\"og:description\" content=\"NUUN VILLA Escala del modelo: 1:50 Tama\u00f1o del modelo: 200 X 160 X 21,5 (L X A) CM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimar Models\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T13:24:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/\",\"url\":\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/\",\"name\":\"Villa Nuun - Mimar Models\",\"isPartOf\":{\"@id\":\"https:\/\/mimarmodels.sa\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg\",\"datePublished\":\"2024-12-10T10:35:25+00:00\",\"dateModified\":\"2025-05-05T13:24:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#primaryimage\",\"url\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg\",\"contentUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimarmodels.sa\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villa Nuun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimarmodels.sa\/es\/#website\",\"url\":\"https:\/\/mimarmodels.sa\/es\/\",\"name\":\"Mimar Models\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mimarmodels.sa\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimarmodels.sa\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimarmodels.sa\/es\/#organization\",\"name\":\"Mimar Models\",\"url\":\"https:\/\/mimarmodels.sa\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mimarmodels.sa\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg\",\"contentUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg\",\"width\":250,\"height\":76,\"caption\":\"Mimar Models\"},\"image\":{\"@id\":\"https:\/\/mimarmodels.sa\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa Nuun - Mimar Models","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/","og_locale":"es_ES","og_type":"article","og_title":"Villa Nuun - Mimar Models","og_description":"NUUN VILLA Escala del modelo: 1:50 Tama\u00f1o del modelo: 200 X 160 X 21,5 (L X A) CM","og_url":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/","og_site_name":"Mimar Models","article_modified_time":"2025-05-05T13:24:43+00:00","og_image":[{"width":1080,"height":606,"url":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/","url":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/","name":"Villa Nuun - Mimar Models","isPartOf":{"@id":"https:\/\/mimarmodels.sa\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#primaryimage"},"image":{"@id":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#primaryimage"},"thumbnailUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg","datePublished":"2024-12-10T10:35:25+00:00","dateModified":"2025-05-05T13:24:43+00:00","breadcrumb":{"@id":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimarmodels.sa\/es\/villa-nuun\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#primaryimage","url":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg","contentUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/12\/Nuun-Villa-01.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/mimarmodels.sa\/es\/villa-nuun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimarmodels.sa\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Villa Nuun"}]},{"@type":"WebSite","@id":"https:\/\/mimarmodels.sa\/es\/#website","url":"https:\/\/mimarmodels.sa\/es\/","name":"Mimar Models","description":"","publisher":{"@id":"https:\/\/mimarmodels.sa\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimarmodels.sa\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mimarmodels.sa\/es\/#organization","name":"Mimar Models","url":"https:\/\/mimarmodels.sa\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mimarmodels.sa\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg","contentUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg","width":250,"height":76,"caption":"Mimar Models"},"image":{"@id":"https:\/\/mimarmodels.sa\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mimarmodels.sa\/es\/wp-json\/wp\/v2\/pages\/26223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mimarmodels.sa\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mimarmodels.sa\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mimarmodels.sa\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mimarmodels.sa\/es\/wp-json\/wp\/v2\/comments?post=26223"}],"version-history":[{"count":8,"href":"https:\/\/mimarmodels.sa\/es\/wp-json\/wp\/v2\/pages\/26223\/revisions"}],"predecessor-version":[{"id":29994,"href":"https:\/\/mimarmodels.sa\/es\/wp-json\/wp\/v2\/pages\/26223\/revisions\/29994"}],"wp:attachment":[{"href":"https:\/\/mimarmodels.sa\/es\/wp-json\/wp\/v2\/media?parent=26223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}