{"id":27269,"date":"2024-11-14T10:42:17","date_gmt":"2024-11-14T10:42:17","guid":{"rendered":"https:\/\/mimarmodels.sa\/clients\/"},"modified":"2025-04-21T17:04:12","modified_gmt":"2025-04-21T17:04:12","slug":"clients","status":"publish","type":"page","link":"https:\/\/mimarmodels.sa\/fr\/clients\/","title":{"rendered":"Clients"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27269\" class=\"elementor elementor-27269 elementor-1202\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-345aac5 e-con-full about-banner-sec e-flex e-con e-parent\" data-id=\"345aac5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21b4c4b e-flex e-con-boxed e-con e-parent\" data-id=\"21b4c4b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0278f40 e-con-full e-flex e-con e-child\" data-id=\"0278f40\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8aa286f elementor-widget elementor-widget-image\" data-id=\"8aa286f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"33\" height=\"1\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/Line-15.svg\" class=\"attachment-full size-full wp-image-983\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2377eb5 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"2377eb5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">NOS CLIENTS<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bb3918 e-flex e-con-boxed e-con e-parent\" data-id=\"4bb3918\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f695dc2 gallery-spacing-custom logo-img elementor-widget elementor-widget-image-gallery\" data-id=\"f695dc2\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-27269 gallery-columns-6 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"213\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/omniyat.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"213\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/orienal_perls.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/dubai-sports-city.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/mag.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/ai-barabari.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/myden.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/expo-2020.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/majid-ali-futtain.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/dubai.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/klindiest.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/al-thuriah.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/ellington.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/arada.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/aldar.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/eagle-hills.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/shurooq.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/diriyah.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"116\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/nisham.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/invest.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/masdar-city.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/damac.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/emaar.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/peace-homes.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/ellington-1.webp\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/mubadala.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/dubai-electricity.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/al-jurf.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/ae7.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/alzorah.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/bg.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/killa.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/retal.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/lacasa.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/neom.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/refine.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/the-heart-of-europe.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/wasi-properties.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/stantec.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/zazen.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/aedas.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/oc.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/fortune5.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/darglobal.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/bukhatir-group.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/ethad-rail.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/ithra-dubai.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/samana-developers.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/orascoma.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/sheikh-zayed-grand-mosque-centre.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/dubai-industrial-city.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/daep.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/tilal.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/dubai-south.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/dubai-police.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/dubai-properties.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/imkan.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/union-properties.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/althuraya.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/bareeq.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/imitiaz-developments.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/bloom.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/nakheel.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/one-zabeel.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/101-group.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/laguna-dha-city.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/birla-estates.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/eywa-dubai.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/four-seasons.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/holding.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/rak-properties.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/rahman-island.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/royal-development-company.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/stregis-hotel-and-resort.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/taraf.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/ua.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/binghatti.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/khatib-alami.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/empire-developments.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/difc.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/morganti.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/sls-dubai.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/innocean-worldwide-2.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"176\" height=\"117\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/dmcc-dubai.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95e1dd8 elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"95e1dd8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f8f8daf e-con-full e-flex e-con e-child\" data-id=\"f8f8daf\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f22025 elementor-widget elementor-widget-image\" data-id=\"5f22025\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/omniyat-1.webp\" class=\"attachment-large size-large wp-image-2056\" alt=\"omniyat\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-daa6d55 e-con-full e-flex e-con e-child\" data-id=\"daa6d55\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-714e433 elementor-widget elementor-widget-image\" data-id=\"714e433\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/oriental-pearls-1.webp\" class=\"attachment-large size-large wp-image-2057\" alt=\"oriental-pearls\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-327c4cc e-con-full e-flex e-con e-child\" data-id=\"327c4cc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41840d3 elementor-widget elementor-widget-image\" data-id=\"41840d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/mag-1.webp\" class=\"attachment-large size-large wp-image-2059\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30b0f9b e-con-full e-flex e-con e-child\" data-id=\"30b0f9b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd5778d elementor-widget elementor-widget-image\" data-id=\"bd5778d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"111\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/al-barari-dubai-1.webp\" class=\"attachment-large size-large wp-image-2063\" alt=\"al barari dubai\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e27f1e4 e-con-full e-flex e-con e-child\" data-id=\"e27f1e4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d87c95 elementor-widget elementor-widget-image\" data-id=\"0d87c95\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/meydan-1.webp\" class=\"attachment-large size-large wp-image-2067\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6dcd7d e-con-full e-flex e-con e-child\" data-id=\"e6dcd7d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83f63c9 elementor-widget elementor-widget-image\" data-id=\"83f63c9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"110\" src=\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/expo-2020-dubai-uae.png\" class=\"attachment-large size-large wp-image-2070\" alt=\"expo 2020 dubai uae\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>NOS CLIENTS<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-27269","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Clients - Mimar Models<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimarmodels.sa\/fr\/clients\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clients - Mimar Models\" \/>\n<meta property=\"og:description\" content=\"NOS CLIENTS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimarmodels.sa\/fr\/clients\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimar Models\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T17:04:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimarmodels.sa\/fr\/clients\/\",\"url\":\"https:\/\/mimarmodels.sa\/fr\/clients\/\",\"name\":\"Clients - Mimar Models\",\"isPartOf\":{\"@id\":\"https:\/\/mimarmodels.sa\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimarmodels.sa\/fr\/clients\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimarmodels.sa\/fr\/clients\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/Line-15.svg\",\"datePublished\":\"2024-11-14T10:42:17+00:00\",\"dateModified\":\"2025-04-21T17:04:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mimarmodels.sa\/fr\/clients\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimarmodels.sa\/fr\/clients\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mimarmodels.sa\/fr\/clients\/#primaryimage\",\"url\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/Line-15.svg\",\"contentUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/Line-15.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimarmodels.sa\/fr\/clients\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mimarmodels.sa\/fr\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clients\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimarmodels.sa\/fr\/#website\",\"url\":\"https:\/\/mimarmodels.sa\/fr\/\",\"name\":\"Mimar Models\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mimarmodels.sa\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mimarmodels.sa\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimarmodels.sa\/fr\/#organization\",\"name\":\"Mimar Models\",\"url\":\"https:\/\/mimarmodels.sa\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mimarmodels.sa\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg\",\"contentUrl\":\"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg\",\"width\":250,\"height\":76,\"caption\":\"Mimar Models\"},\"image\":{\"@id\":\"https:\/\/mimarmodels.sa\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clients - Mimar Models","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimarmodels.sa\/fr\/clients\/","og_locale":"fr_FR","og_type":"article","og_title":"Clients - Mimar Models","og_description":"NOS CLIENTS","og_url":"https:\/\/mimarmodels.sa\/fr\/clients\/","og_site_name":"Mimar Models","article_modified_time":"2025-04-21T17:04:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mimarmodels.sa\/fr\/clients\/","url":"https:\/\/mimarmodels.sa\/fr\/clients\/","name":"Clients - Mimar Models","isPartOf":{"@id":"https:\/\/mimarmodels.sa\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimarmodels.sa\/fr\/clients\/#primaryimage"},"image":{"@id":"https:\/\/mimarmodels.sa\/fr\/clients\/#primaryimage"},"thumbnailUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/Line-15.svg","datePublished":"2024-11-14T10:42:17+00:00","dateModified":"2025-04-21T17:04:12+00:00","breadcrumb":{"@id":"https:\/\/mimarmodels.sa\/fr\/clients\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimarmodels.sa\/fr\/clients\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mimarmodels.sa\/fr\/clients\/#primaryimage","url":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/Line-15.svg","contentUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/Line-15.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/mimarmodels.sa\/fr\/clients\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mimarmodels.sa\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Clients"}]},{"@type":"WebSite","@id":"https:\/\/mimarmodels.sa\/fr\/#website","url":"https:\/\/mimarmodels.sa\/fr\/","name":"Mimar Models","description":"","publisher":{"@id":"https:\/\/mimarmodels.sa\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mimarmodels.sa\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mimarmodels.sa\/fr\/#organization","name":"Mimar Models","url":"https:\/\/mimarmodels.sa\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mimarmodels.sa\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg","contentUrl":"https:\/\/mimarmodels.sa\/wp-content\/uploads\/2024\/11\/logo-mimar.svg","width":250,"height":76,"caption":"Mimar Models"},"image":{"@id":"https:\/\/mimarmodels.sa\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mimarmodels.sa\/fr\/wp-json\/wp\/v2\/pages\/27269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mimarmodels.sa\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mimarmodels.sa\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mimarmodels.sa\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mimarmodels.sa\/fr\/wp-json\/wp\/v2\/comments?post=27269"}],"version-history":[{"count":1,"href":"https:\/\/mimarmodels.sa\/fr\/wp-json\/wp\/v2\/pages\/27269\/revisions"}],"predecessor-version":[{"id":27270,"href":"https:\/\/mimarmodels.sa\/fr\/wp-json\/wp\/v2\/pages\/27269\/revisions\/27270"}],"wp:attachment":[{"href":"https:\/\/mimarmodels.sa\/fr\/wp-json\/wp\/v2\/media?parent=27269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}